{"id":10526,"date":"2016-01-09T09:00:27","date_gmt":"2016-01-09T08:00:27","guid":{"rendered":"https:\/\/www.lasociedadgeografica.com\/blog\/?p=10526"},"modified":"2017-02-09T12:00:20","modified_gmt":"2017-02-09T11:00:20","slug":"hoteles-oberoi-en-india","status":"publish","type":"post","link":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/","title":{"rendered":"Hoteles Oberoi en India, reinventando su legado"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;10526&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;6&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Hoteles Oberoi en India, reinventando su legado&quot;,&quot;width&quot;:&quot;137&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 137px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n<p>Escrito por: Enric Donate<\/p>\n<h4 style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">Los hoteles Oberoi en India llevan 80 a\u00f1os creando experiencias para que dormir en una de sus propiedades de lujo sea inolvidable. Contar con el mejor hotel del mundo 2015, Udaivilas en Udaipur, es el mejor ejemplo de su excelencia.<\/span><\/i><\/h4>\n<div id=\"attachment_10528\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><a href=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"Hoteles Oberoi en India wp-image-10528 size-large\" title=\"Hoteles Oberoi en India\" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-1024x512.jpg\" alt=\"Hoteles Oberoi en India\" width=\"728\" height=\"364\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-1024x512.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-300x150.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-728x364.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-363x182.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-462x231.jpg 462w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels.jpg 1920w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Oberoi Hotels<\/p><\/div>\n<p><span style=\"font-weight: 400;\">La familia Oberoi est\u00e1 detr\u00e1s de <strong>una de las cadenas hoteleras m\u00e1s prestigiosas y exclusivas de India<\/strong>. Hoteles Oberoi en India es una marca camale\u00f3nica que se adapta al medio con hoteles urbanos en rascacielos modernos, propiedades en ciudades hist\u00f3ricas de Rajast\u00e1n que evocan la arquitectura principesca o exclusivos resorts en parques naturales totalmente integrados en la jungla. En los <\/span><span style=\"font-weight: 400;\">hoteles de la cadena Oberoi<\/span><span style=\"font-weight: 400;\"> todo gira en torno a la <strong>creaci\u00f3n de experiencias \u00fanicas y, por ello, el cuidado al detalle y la cortes\u00eda son constantes<\/strong>. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los <\/span><a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-en-india\/\" target=\"_blank\"><span style=\"font-weight: 400;\">hoteles <\/span><\/a><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-en-india\/\" target=\"_blank\">en India<\/a> saben sacar partido de sus excelentes ubicaciones. <\/span><span style=\"font-weight: 400;\">Amarvilas<\/span><span style=\"font-weight: 400;\"> a los pies del Taj Mahal ofrece <strong>vistas panor\u00e1micas del mayor monumento construido al amor<\/strong> desde cada una de las habitaciones. Adem\u00e1s de la visita al complejo del Taj en coches privados, puedes disfrutar una cena a la luz de las velas en sus espectaculares jardines con la suave silueta del Taj iluminado por la luna. <\/span><\/p>\n<div id=\"attachment_10527\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><a href=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"Hoteles Oberoi en India wp-image-10527 size-large\" title=\"Hoteles Oberoi en India\" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels-1024x512.jpg\" alt=\"Hoteles Oberoi en India\" width=\"728\" height=\"364\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels-1024x512.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels-300x150.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels-728x364.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels-363x182.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels-462x231.jpg 462w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Kohinoor-Suite-Oberoi-Amarvilas-Agra-C-Oberoi-Hotels.jpg 1920w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Oberoi Hotels<\/p><\/div>\n<p><span style=\"font-weight: 400;\"><strong>Elegido como el mejor hotel del mundo por Leisure + Travel en 2015<\/strong>, el hotel Oberoi Udaivilas en Udaipur se extiende por una <strong>antigua reserva de caza del maharan\u00e1<\/strong> que todav\u00eda conserva su fauna salvaje. La arquitectura del complejo se inspira en la ciudad de Udaipur, con sus patios, terrazas y c\u00fapulas, aprovechando las <strong>vistas privilegiadas desde la orilla del lago Pichola<\/strong>. El hotel est\u00e1 pensado para rom\u00e1nticas\u00a0<a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/actividades\/luna-de-miel-en-india\/\" target=\"_blank\">lunas de miel <\/a>con cenas en c\u00fapulas privadas o almuerzos en rincones del lago. Asimismo, ofrece un amplio programa para viajar a Udaipur en familia, desde talleres de cometas a como atarse un turbante \u00a0hasta paseos en camello decorado por caminos secretos de la propiedad.<\/span><\/p>\n<div id=\"attachment_10529\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><a href=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"Hoteles Oberoi en India wp-image-10529 size-large\" title=\"Hoteles Oberoi en India\" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2-1024x512.jpg\" alt=\"Hoteles Oberoi en India\" width=\"728\" height=\"364\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2-1024x512.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2-300x150.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2-728x364.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2-363x182.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2-462x231.jpg 462w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-Udaipur-c-Oberoi-Hotels-2.jpg 1920w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Oberoi Hotels<\/p><\/div>\n<p><span style=\"font-weight: 400;\">En Jaipur, el <\/span><span style=\"font-weight: 400;\">Rajvilas<\/span><span style=\"font-weight: 400;\"> est\u00e1 construido <strong>alrededor de un antiguo templo de Shiva<\/strong> donde practicar sesiones de yoga al amanecer. La arquitectura es protagonista en el Oberoi de la <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/monumentos\/el-origen-del-color-de-jaipur-la-ciudad-rosa-de-la-india\/\" target=\"_blank\">Ciudad Rosa de Jaipur<\/a>, un hotel que desvela la grandeza y el estilo de vida principesca en la capital de Rajast\u00e1n. Pensando en experiencias inolvidables, podr\u00e1s recrear tus votos matrimoniales con una verdadera ceremonia hind\u00fa en sus elegantes jardines. El hotel ofrece adem\u00e1s <strong>safaris a lomos de elefante hasta el fuerte de Naila<\/strong> donde disfrutar\u00e1s de un exclusivo picnic.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La vida de los pr\u00edncipes indios no estaba completa sin la caza. Sus reservas son hoy <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/naturaleza\/parques-naturales-de-india-lugares-de-cuento\/\" target=\"_blank\">grandes parques naturales<\/a> como Ranthambore, <strong>espacios donde encontrar en libertad <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/tigres-en-el-corazon-de-la-india\/\" target=\"_blank\">tigre de Bengala<\/a><\/strong>. All\u00ed el hotel<\/span><span style=\"font-weight: 400;\"> Oberoi Vanyavilas<\/span><span style=\"font-weight: 400;\"> demuestra el<strong> respeto por el entorno que caracteriza a la cadena<\/strong> y el lujo de vivir en una tienda digna de un maharaj\u00e1. Los safaris de madrugada y al atardecer con expertos naturalistas para seguir las huellas del gran felino, se completan con la oferta del hotel que no escatima en los exquisitos servicios y hospitalidad propios de los <\/span><span style=\"font-weight: 400;\">hoteles de la cadena Oberoi<\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<div id=\"attachment_10530\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><a href=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"Hoteles Oberoi en India wp-image-10530 size-large\" title=\"Hoteles Oberoi en India\" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels-1024x512.jpg\" alt=\"Hoteles Oberoi en India\" width=\"728\" height=\"364\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels-1024x512.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels-300x150.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels-728x364.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels-363x182.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels-462x231.jpg 462w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Vanyavilas-Ranthambore-Tiger-Reserve-c-Oberoi-Hotels.jpg 1920w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Oberoi Hotels<\/p><\/div>\n<p><span style=\"font-weight: 400;\">Independientemente del lugar, ya sea Delhi, Mumbai, Kolkata, Agra, Udaipur o Jaipur, los <\/span><strong>hoteles Oberoi en India<\/strong><span style=\"font-weight: 400;\"><strong> son sin\u00f3nimo de localizaciones espectaculares, trato exquisito y experiencias \u00fanicas e inolvidables<\/strong> garantizadas por la nueva generaci\u00f3n de la familia Oberoi que guarda celosa el legado de sus antepasados.<\/span><\/p>\n<div class=\"SGIcontact\"><form id=\"sf_shortcode_SGIcontact_0F\" action=\"\/contacto\/\" method=\"post\" class=\"SGIcontactwidget_form\"><p style=\"text-align:center;font-style:italic;font-size:14px;padding-bottom:10px\" id=\"sf_shortcode_SGIcontact_0FP\">\u00bfQuieres que te dise\u00f1emos un viaje exclusivo al Subcontinente Indio?<\/p>\n<div style=\"text-align:center\" id=\"sf_shortcode_SGIcontact_0FD\"><input type=\"submit\" value=\"Cont\u00e1ctanos Aqu\u00ed\" \/>\n<\/div><\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Escrito por: Enric Donate Los hoteles Oberoi en India llevan 80 a\u00f1os creando experiencias para que dormir en una de sus propiedades de lujo sea inolvidable. Contar con el mejor hotel del mundo 2015, Udaivilas &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1099,7,291,2881],"tags":[194,5123,145,5127,5130,4774,2521,4921,4922,4923,1220,601,3053,2520,2283,180,5125,105,5124,928,435,2218,5126,151,5122,5121,5128,5129],"class_list":["post-10526","post","type-post","status-publish","format-standard","hentry","category-destinos","category-hoteles","category-lujo","category-viajes-india","tag-agra","tag-amarvilas","tag-delhi","tag-experiencia-unica-en-india","tag-hotel-5-estrellas-en-india","tag-hoteles-de-lujo-en-el-norte-de-india","tag-hoteles-de-lujo-en-india","tag-hoteles-de-lujo-en-parques-naturales","tag-hoteles-de-lujo-para-lunas-de-miel","tag-hoteles-de-lujo-para-viajar-con-ninos","tag-india","tag-jaipur","tag-kolkata","tag-lujo-en-india","tag-luna-de-miel-en-india","tag-mumbai","tag-parques-naturales-india","tag-rajastan","tag-rajvilas","tag-ranthambore","tag-taj-mahal","tag-tigre-de-bengala","tag-tigre-en-india","tag-udaipur","tag-udaivilas","tag-vanyavilas","tag-viajar-con-ninos-a-india","tag-viaje-de-novios-india"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoteles Oberoi en India, reintentando su gran legado<\/title>\n<meta name=\"description\" content=\"Los hoteles Oberoi en India se integran en el medio: los encontrar\u00e1s en rascacielos urbanos, en edificios hist\u00f3ricos o en resorts en parques naturales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoteles Oberoi en India, reintentando su gran legado\" \/>\n<meta property=\"og:description\" content=\"Los hoteles Oberoi en India se integran en el medio: los encontrar\u00e1s en rascacielos urbanos, en edificios hist\u00f3ricos o en resorts en parques naturales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de viajes a India\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-09T08:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-09T11:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-1024x512.jpg\" \/>\n<meta name=\"author\" content=\"SGI\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SGI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/\"},\"author\":{\"name\":\"SGI\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"headline\":\"Hoteles Oberoi en India, reinventando su legado\",\"datePublished\":\"2016-01-09T08:00:27+00:00\",\"dateModified\":\"2017-02-09T11:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/\"},\"wordCount\":605,\"commentCount\":0,\"keywords\":[\"agra\",\"Amarvilas\",\"delhi\",\"experiencia \u00fanica en India\",\"hotel 5 estrellas en India\",\"hoteles de lujo en el Norte de India\",\"hoteles de lujo en India\",\"hoteles de lujo en parques naturales\",\"hoteles de lujo para lunas de miel\",\"hoteles de lujo para viajar con ni\u00f1os\",\"India\",\"Jaipur\",\"Kolkata\",\"lujo en India\",\"luna de miel en India\",\"Mumbai\",\"parques naturales India\",\"rajast\u00e1n\",\"Rajvilas\",\"Ranthambore\",\"Taj Mahal\",\"tigre de bengala\",\"tigre en India\",\"udaipur\",\"Udaivilas\",\"Vanyavilas\",\"viajar con ni\u00f1os a India\",\"viaje de novios India\"],\"articleSection\":[\"Destinos\",\"Hoteles\",\"Lujo\",\"Viajes India\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/\",\"name\":\"Hoteles Oberoi en India, reintentando su gran legado\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\"},\"datePublished\":\"2016-01-09T08:00:27+00:00\",\"dateModified\":\"2017-02-09T11:00:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"description\":\"Los hoteles Oberoi en India se integran en el medio: los encontrar\u00e1s en rascacielos urbanos, en edificios hist\u00f3ricos o en resorts en parques naturales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/hoteles\\\/hoteles-oberoi-en-india\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoteles Oberoi en India, reinventando su legado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\",\"name\":\"Blog de viajes a India\",\"description\":\"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\",\"name\":\"SGI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"caption\":\"SGI\"},\"description\":\"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\\\/\\\/www.lasociedadgeografica.com\",\"sameAs\":[\"https:\\\/\\\/www.lasociedadgeografica.com\"],\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoteles Oberoi en India, reintentando su gran legado","description":"Los hoteles Oberoi en India se integran en el medio: los encontrar\u00e1s en rascacielos urbanos, en edificios hist\u00f3ricos o en resorts en parques naturales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/","og_locale":"es_ES","og_type":"article","og_title":"Hoteles Oberoi en India, reintentando su gran legado","og_description":"Los hoteles Oberoi en India se integran en el medio: los encontrar\u00e1s en rascacielos urbanos, en edificios hist\u00f3ricos o en resorts en parques naturales.","og_url":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/","og_site_name":"Blog de viajes a India","article_published_time":"2016-01-09T08:00:27+00:00","article_modified_time":"2017-02-09T11:00:20+00:00","og_image":[{"url":"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2015\/12\/Post-5-Noviembre-Hoteles-de-la-cadena-Oberoi-Oberoi-Udaivilas-c-Oberoi-Hotels-1024x512.jpg","type":"","width":"","height":""}],"author":"SGI","twitter_misc":{"Escrito por":"SGI","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/#article","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/"},"author":{"name":"SGI","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"headline":"Hoteles Oberoi en India, reinventando su legado","datePublished":"2016-01-09T08:00:27+00:00","dateModified":"2017-02-09T11:00:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/"},"wordCount":605,"commentCount":0,"keywords":["agra","Amarvilas","delhi","experiencia \u00fanica en India","hotel 5 estrellas en India","hoteles de lujo en el Norte de India","hoteles de lujo en India","hoteles de lujo en parques naturales","hoteles de lujo para lunas de miel","hoteles de lujo para viajar con ni\u00f1os","India","Jaipur","Kolkata","lujo en India","luna de miel en India","Mumbai","parques naturales India","rajast\u00e1n","Rajvilas","Ranthambore","Taj Mahal","tigre de bengala","tigre en India","udaipur","Udaivilas","Vanyavilas","viajar con ni\u00f1os a India","viaje de novios India"],"articleSection":["Destinos","Hoteles","Lujo","Viajes India"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/","url":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/","name":"Hoteles Oberoi en India, reintentando su gran legado","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website"},"datePublished":"2016-01-09T08:00:27+00:00","dateModified":"2017-02-09T11:00:20+00:00","author":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"description":"Los hoteles Oberoi en India se integran en el medio: los encontrar\u00e1s en rascacielos urbanos, en edificios hist\u00f3ricos o en resorts en parques naturales.","breadcrumb":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/hoteles\/hoteles-oberoi-en-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lasociedadgeografica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Hoteles Oberoi en India, reinventando su legado"}]},{"@type":"WebSite","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website","url":"https:\/\/www.lasociedadgeografica.com\/blog\/","name":"Blog de viajes a India","description":"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasociedadgeografica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2","name":"SGI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","caption":"SGI"},"description":"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\/\/www.lasociedadgeografica.com","sameAs":["https:\/\/www.lasociedadgeografica.com"],"url":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/10526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/comments?post=10526"}],"version-history":[{"count":6,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/10526\/revisions"}],"predecessor-version":[{"id":14030,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/10526\/revisions\/14030"}],"wp:attachment":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/media?parent=10526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/categories?post=10526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/tags?post=10526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}