{"id":10918,"date":"2016-06-06T09:00:33","date_gmt":"2016-06-06T07:00:33","guid":{"rendered":"https:\/\/www.lasociedadgeografica.com\/blog\/?p=10918"},"modified":"2017-05-26T09:48:25","modified_gmt":"2017-05-26T07:48:25","slug":"especias-de-india","status":"publish","type":"post","link":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/","title":{"rendered":"Especias de India: cu\u00e1les son y c\u00f3mo usarlas"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;10918&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;165&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;6&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.5\\\/5 - (165 votos)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Especias de India: cu\u00e1les son y c\u00f3mo usarlas&quot;,&quot;width&quot;:&quot;123&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 123px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            4.5\/5 - (165 votos)    <\/div>\n    <\/div>\n<p><i><span style=\"font-weight: 400;\">Las especias de India son el ingrediente estrella de toda su gastronom\u00eda y le aportan un sabor y olor \u00fanicos que hacen que su cocina sea reconocible en todo el mundo.<\/span><\/i><\/p>\n<p>Escrito por: Lorena P\u00e9rez<br \/>\n<a name=\"smore-\"><\/a><br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/DSgoAMZJ8GM\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Si hay algo en lo que todo el mundo coincide al viajar a la India es el olor a especias e incienso que impregna el ambiente. <strong>Las especias de India son un ingrediente imprescindible en la cocina<\/strong> gracias a su aroma, sabor e, incluso, color. Todos sabemos que <strong>existen cientos de especias diferentes<\/strong>, cada una indicada para un tipo de producto distinto, e incluso pueden realizarse <a href=\"\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/ruta-de-las-especias-por-la-india\/\" target=\"_blank\" rel=\"noopener noreferrer\">rutas de las especias<\/a> pero, \u00bfsabes cu\u00e1les son las especias de India m\u00e1s comunes?<\/p>\n<h3><strong>Conoce las especias de India m\u00e1s utilizadas<\/strong><\/h3>\n<p>La cocina india es capaz de mezclar en sus platos todo tipo de especias hasta llegar a conquistar los paladares m\u00e1s exigentes. Muchas de esas especias de India son mundialmente conocidas y utilizadas, como por ejemplo la <strong>cayena con su caracter\u00edstico sabor picante<\/strong>, el comino de sabor m\u00e1s amargo, <strong>el clavo arom\u00e1tico<\/strong> y picante o <strong>el cilantro que aporta toques agridulces<\/strong>. Todas ellas se utilizan en la preparaci\u00f3n de currys y pueden agregarse tanto a sopas y guisos como a carnes y verduras. Mundialmente conocidos son tambi\u00e9n <strong>el azafr\u00e1n y la albahaca<\/strong>, que combinan sobre todo con pastas y arroces y, por supuesto, <strong>la canela y el cardamomo<\/strong>, utilizados en la gastronom\u00eda india en postres y dulces.<\/p>\n<div id=\"attachment_10920\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><img loading=\"lazy\" decoding=\"async\" class=\"Especias de India - Cardamono wp-image-10920 size-large\" title=\"Especias de India - Cardamono \" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-1024x726.jpg\" alt=\"Especias de India - Cardamono \" width=\"728\" height=\"516\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-1024x726.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-300x213.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-768x545.jpg 768w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-728x516.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-363x257.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-462x328.jpg 462w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB.jpg 2048w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><p class=\"wp-caption-text\">\u00a9MAURO CATEB<\/p><\/div>\n<p>Pero existen muchas m\u00e1s especias de India que las que todos conocemos y que aportan a sus platos un toque \u00fanico y singular. Una de ellas es <strong>la alholva, una semilla de color rojo<\/strong>, muy crujiente y con un ligero toque amargo, principal ingrediente en la mayor\u00eda de currys y utilizada tambi\u00e9n en pan y galletas. Tambi\u00e9n encontramos <strong>la c\u00farcuma, sustituto del azafr\u00e1n<\/strong>, con un sabor similar a la pimienta y conocida como \u201cla sal de oriente\u201d por potenciar el sabor de todo tipo de platos. Por otro lado est\u00e1 <strong>la asaf\u00e9tida, tambi\u00e9n llamada hing<\/strong>, con un sabor muy picante y un olor atrufado, perfecta para carnes y arroces. Y por \u00faltimo <strong>el jengibre, una ra\u00edz que se usa tanto fresca como seca<\/strong> y que aporta un sabor refrescante y un poco picante a carnes, salsas, currys y legumbres.<\/p>\n<div id=\"attachment_10921\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><img loading=\"lazy\" decoding=\"async\" class=\"Especias de India - Curcuma wp-image-10921 size-large\" title=\"Especias de India - Curcuma \" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Curcuma-cJoachim-Schlosser-1024x683.jpg\" alt=\"Especias de India - Curcuma \" width=\"728\" height=\"486\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Curcuma-cJoachim-Schlosser.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Curcuma-cJoachim-Schlosser-300x200.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Curcuma-cJoachim-Schlosser-768x512.jpg 768w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Curcuma-cJoachim-Schlosser-728x486.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Curcuma-cJoachim-Schlosser-363x242.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Curcuma-cJoachim-Schlosser-462x308.jpg 462w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><p class=\"wp-caption-text\">\u00a9Joachim Schlosser<\/p><\/div>\n<h3><strong><em>Masala<\/em> y currys: las especias de India tambi\u00e9n se mezclan<\/strong><\/h3>\n<p>Pero en los platos indios es muy dif\u00edcil que se utilice una sola especia, lo m\u00e1s habitual es encontrar una elaboraci\u00f3n con <strong><em>masala<\/em>, literalmente \u201cmezcla de especias\u201d<\/strong>. Entre las <em>masala<\/em> m\u00e1s utilizadas encontramos:<br \/>\n<em><strong>&#8211; Garam masala:<\/strong><\/em> una mezcla de especias bastante picantes que <strong>puede encontrarse ya preparada<\/strong> en los mercados de especias de India. Esta receta es una mezcla de cardamomo, ajo, pimienta y canela y se utiliza en todo tipo de carnes, verduras, legumbres y guisos.<br \/>\n<em><strong>&#8211; Tandoori masala:<\/strong><\/em> seguro que te suena el pollo tandoori, pero esta mezcla de comino, cilantro, ajo y alholva \u2013entre otras especias- se puede encontrar <strong>en un sinf\u00edn platos de cocina India y pakistan\u00ed,<\/strong> sobre todo en <a href=\"\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/5-platos-vegetarianos-de-la-india-que-debes-probar\/\" target=\"_blank\" rel=\"noopener noreferrer\">platos vegetarianos<\/a> y de carne.<\/p>\n<div id=\"attachment_10919\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><img loading=\"lazy\" decoding=\"async\" class=\"Especias de India - Pollo Tandoori wp-image-10919 size-large\" title=\"Especias de India - Pollo Tandoori\" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Pollo-Tandoori-cstu_spivack-1024x681.jpg\" alt=\"Especias de India - Pollo Tandoori\" width=\"728\" height=\"484\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Pollo-Tandoori-cstu_spivack.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Pollo-Tandoori-cstu_spivack-300x200.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Pollo-Tandoori-cstu_spivack-768x511.jpg 768w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Pollo-Tandoori-cstu_spivack-728x484.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Pollo-Tandoori-cstu_spivack-363x241.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Pollo-Tandoori-cstu_spivack-462x307.jpg 462w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><p class=\"wp-caption-text\">\u00a9stu_spivack<\/p><\/div>\n<p>Y por \u00faltimo una de las mezclas m\u00e1s conocidas y utilizadas en la gastronom\u00eda de India: los currys. <strong>Existen multitud de formas y variantes de currys<\/strong>, que van desde muy picantes hasta los m\u00e1s suaves. Los m\u00e1s habituales son:<br \/>\n<em><strong>&#8211; Vindaloo:<\/strong><\/em> el rey de los currys, mezcla perfecta de varios ingredientes entre los que destacan el jengibre, cardamomo, canela y la pimienta. Tiene un matiz muy picante y se utiliza principalmente <strong>para marinar carnes, sobre todo cordero y pollo<\/strong>.<br \/>\n<strong><em>&#8211; Madr\u00e1s:<\/em><\/strong> este curry <strong>de color rojo muy picante es utilizado en carnes<\/strong>, aunque tambi\u00e9n combina a la perfecci\u00f3n con verduras y arroces. Para elaborarse se mezcla piment\u00f3n, cayena, c\u00farcuma, tomate, jengibre y otro tipo de especias de India.<\/p>\n<div id=\"attachment_10923\" class=\"wp-caption aligncenter\" style=\"width: 728px\"><img loading=\"lazy\" decoding=\"async\" class=\"Especias de India wp-image-10923 size-large\" title=\"Especias de India \" src=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio-1024x683.jpg\" alt=\"Especias de India \" width=\"728\" height=\"486\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio-1024x683.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio-300x200.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio-768x512.jpg 768w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio-728x485.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio-363x242.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio-462x308.jpg 462w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-cSeba-Della-y-Sole-Bossio.jpg 2048w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><p class=\"wp-caption-text\">\u00a9Seba Della y Sole Bossio<\/p><\/div>\n<p>Ahora ya conoces las diferentes especias que puedes encontrar en la cocina india, solo tienes que decidirte a probar cada uno de los platos que las llevan. \u00a1Buen provecho!<\/p>\n<p>&nbsp;<\/p>\n<div class=\"SGIcontact\"><form id=\"sf_shortcode_SGInews_0F\" onsubmit=\"event.preventDefault();return false;\" class=\"SGIcontactwidget_form\" style=\"text-align:center\"><p style=\"text-align:center;font-style:italic;font-size:14px;padding-bottom:10px;\" id=\"sf_shortcode_SGInews_0FP\">\u00bfSab\u00edas que la selecci\u00f3n oficial de f\u00fatbol de But\u00e1n es una de las dos peores del mundo?<\/p>\n<p style=\"padding-bottom:10px;color:#333;font-style:italic;font-size:14px;\" id=\"sf_shortcode_SGInews_0FP1\">Ent\u00e9rate Aqu\u00ed<\/p>\n<p style=\"text-align:center;font-style:italic;font-size:14px;padding-bottom:10px;display:none;color:#009900\" id=\"sf_shortcode_SGInews_0FP2\">A continuaci\u00f3n te ofrecemos la suscripci\u00f3n gratuita a un Bolet\u00edn de Noticias repleto de ideas y sugerencias para viajar a India.<br><br>\n                  \u00a1Disfr\u00fatalo!<br>Podr\u00e1s dejar de recibirlo cuando quieras.<\/p>\n<div id=\"sf_shortcode_SGInews_0FD\"><p id=\"sf_shortcode_SGInews_0FP3\" style=\"text-align:left\"><label for=\"nombre\">Tu nombre<\/label><br \/><input type=\"text\" name=\"nombre\" class=\"input\" \/><\/p>\n<p id=\"sf_shortcode_SGInews_0FP4\" style=\"text-align:left\"><label for=\"email\">Tu e-mail<\/label><br \/><input type=\"text\" name=\"email\" class=\"input\" \/><\/p>\n<p id=\"sf_shortcode_SGInews_0FP5\" style=\"text-align:left\"><input type=\"checkbox\" name=\"agree\" style=\"width:auto;margin:0;padding:0\" onchange=\"changeAgree(this)\" value=\"1\" class=\"agreeCheckBox\" \/>&nbsp;&nbsp;Acepto la <a style=\"color: #888;\" href=\"javascript:void(0)\" onclick=\"loadLegalPopup('llPrivacidad');return false;\">Pol\u00edtica de Privacidad<\/a><\/p>\n<input type=\"submit\" name=\"enviar\" value=\"Suscr\u00edbete\" onclick=\"return frmPostNews('sf_shortcode_SGInews_0F');\" \/>\n<\/div><\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las especias de India son el ingrediente estrella de toda su gastronom\u00eda y le aportan un sabor y olor \u00fanicos que hacen que su cocina sea reconocible en todo el mundo. Escrito por: Lorena P\u00e9rez &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1099,6,2881],"tags":[2146,5526,1460,5516,5520,3163,5521,5517,5523,822,5524,3166,5518,5525,5522,5519],"class_list":["post-10918","post","type-post","status-publish","format-standard","hentry","category-destinos","category-gastronomia","category-viajes-india","tag-cocina-india","tag-color-de-india","tag-comer-en-india","tag-condimentos-de-india","tag-currys-de-india","tag-especias-de-india","tag-garam-masala","tag-gastronomia-en-india","tag-ingredientes-de-india","tag-madras","tag-olor-de-india","tag-picante-en-india","tag-platos-tipicos-de-india","tag-sabor-de-india","tag-tandoori-masala","tag-vindaloo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Especias de India: cu\u00e1les son y c\u00f3mo usarlas<\/title>\n<meta name=\"description\" content=\"Las especias de India aportan un toque especial a cada uno de los platos, convirtiendo en \u00fanica cada elaboraci\u00f3n. \u00bfConoces ya cu\u00e1les son?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Especias de India: cu\u00e1les son y c\u00f3mo usarlas\" \/>\n<meta property=\"og:description\" content=\"Las especias de India aportan un toque especial a cada uno de los platos, convirtiendo en \u00fanica cada elaboraci\u00f3n. \u00bfConoces ya cu\u00e1les son?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de viajes a India\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-06T07:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-26T07:48:25+00:00\" \/>\n<meta property=\"og:image\" content=\"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-1024x726.jpg\" \/>\n<meta name=\"author\" content=\"SGI\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SGI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/\"},\"author\":{\"name\":\"SGI\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"headline\":\"Especias de India: cu\u00e1les son y c\u00f3mo usarlas\",\"datePublished\":\"2016-06-06T07:00:33+00:00\",\"dateModified\":\"2017-05-26T07:48:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/\"},\"wordCount\":742,\"commentCount\":4,\"keywords\":[\"cocina india\",\"color de India\",\"comer en India\",\"Condimentos de India\",\"Currys de India\",\"especias de India\",\"Garam masala\",\"Gastronom\u00eda en India\",\"Ingredientes de India\",\"madras\",\"Olor de India\",\"picante en India\",\"Platos t\u00edpicos de India\",\"Sabor de India\",\"Tandoori masala\",\"Vindaloo\"],\"articleSection\":[\"Destinos\",\"Gastronom\u00eda\",\"Viajes India\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/\",\"name\":\"Especias de India: cu\u00e1les son y c\u00f3mo usarlas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\"},\"datePublished\":\"2016-06-06T07:00:33+00:00\",\"dateModified\":\"2017-05-26T07:48:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"description\":\"Las especias de India aportan un toque especial a cada uno de los platos, convirtiendo en \u00fanica cada elaboraci\u00f3n. \u00bfConoces ya cu\u00e1les son?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/gastronomia\\\/especias-de-india\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Especias de India: cu\u00e1les son y c\u00f3mo usarlas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\",\"name\":\"Blog de viajes a India\",\"description\":\"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\",\"name\":\"SGI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"caption\":\"SGI\"},\"description\":\"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\\\/\\\/www.lasociedadgeografica.com\",\"sameAs\":[\"https:\\\/\\\/www.lasociedadgeografica.com\"],\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Especias de India: cu\u00e1les son y c\u00f3mo usarlas","description":"Las especias de India aportan un toque especial a cada uno de los platos, convirtiendo en \u00fanica cada elaboraci\u00f3n. \u00bfConoces ya cu\u00e1les son?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/","og_locale":"es_ES","og_type":"article","og_title":"Especias de India: cu\u00e1les son y c\u00f3mo usarlas","og_description":"Las especias de India aportan un toque especial a cada uno de los platos, convirtiendo en \u00fanica cada elaboraci\u00f3n. \u00bfConoces ya cu\u00e1les son?","og_url":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/","og_site_name":"Blog de viajes a India","article_published_time":"2016-06-06T07:00:33+00:00","article_modified_time":"2017-05-26T07:48:25+00:00","og_image":[{"url":"\/\/www.lasociedadgeografica.com\/blog\/uploads\/2016\/01\/Especias-de-India-Cardamono-cMAURO-CATEB-1024x726.jpg","type":"","width":"","height":""}],"author":"SGI","twitter_misc":{"Escrito por":"SGI","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/#article","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/"},"author":{"name":"SGI","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"headline":"Especias de India: cu\u00e1les son y c\u00f3mo usarlas","datePublished":"2016-06-06T07:00:33+00:00","dateModified":"2017-05-26T07:48:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/"},"wordCount":742,"commentCount":4,"keywords":["cocina india","color de India","comer en India","Condimentos de India","Currys de India","especias de India","Garam masala","Gastronom\u00eda en India","Ingredientes de India","madras","Olor de India","picante en India","Platos t\u00edpicos de India","Sabor de India","Tandoori masala","Vindaloo"],"articleSection":["Destinos","Gastronom\u00eda","Viajes India"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/","url":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/","name":"Especias de India: cu\u00e1les son y c\u00f3mo usarlas","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website"},"datePublished":"2016-06-06T07:00:33+00:00","dateModified":"2017-05-26T07:48:25+00:00","author":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"description":"Las especias de India aportan un toque especial a cada uno de los platos, convirtiendo en \u00fanica cada elaboraci\u00f3n. \u00bfConoces ya cu\u00e1les son?","breadcrumb":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/especias-de-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lasociedadgeografica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Especias de India: cu\u00e1les son y c\u00f3mo usarlas"}]},{"@type":"WebSite","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website","url":"https:\/\/www.lasociedadgeografica.com\/blog\/","name":"Blog de viajes a India","description":"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasociedadgeografica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2","name":"SGI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","caption":"SGI"},"description":"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\/\/www.lasociedadgeografica.com","sameAs":["https:\/\/www.lasociedadgeografica.com"],"url":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/10918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/comments?post=10918"}],"version-history":[{"count":6,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/10918\/revisions"}],"predecessor-version":[{"id":14924,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/10918\/revisions\/14924"}],"wp:attachment":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/media?parent=10918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/categories?post=10918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/tags?post=10918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}