{"id":16372,"date":"2018-02-08T09:05:48","date_gmt":"2018-02-08T08:05:48","guid":{"rendered":"https:\/\/www.lasociedadgeografica.com\/blog\/?p=16372"},"modified":"2018-01-05T10:17:01","modified_gmt":"2018-01-05T09:17:01","slug":"gujarat-estado-de-unesco-india","status":"publish","type":"post","link":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/","title":{"rendered":"Gujarat: magia y monumentos Unesco en India"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;16372&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;6&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;5\\\/5 - (1 voto)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Gujarat: magia y monumentos Unesco en India&quot;,&quot;width&quot;:&quot;137&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 137px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            5\/5 - (1 voto)    <\/div>\n    <\/div>\n<p><i><span class=\"entradilla\">Gujarat es un estado din\u00e1mico situado en el oeste de India, famoso a su vez por su vibrante colorido y su religiosidad, al que se puede acceder f\u00e1cilmente por los aeropuertos internacionales de Delhi, Mumbai o Ahmedabad.<\/span><\/i><\/p>\n<p>Informaci\u00f3n aportada por Incredible India.<br \/>\n<a name=\"smore-\"><\/a><\/p>\n<h3>Gujarat: de patrimonio en patrimonio<\/h3>\n<p>Gujarat est\u00e1 comunicado con el resto del pa\u00eds por una densa <strong>red de ferrocarriles<\/strong>. Geogr\u00e1ficamente,<strong>\u00a0limita con <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/rajastan-en-pareja-10-lugares-mas-romanticos-del-rajastan\/\" target=\"_blank\" rel=\"noopener\">Rajast\u00e1n<\/a><\/strong>. <strong>La mejor \u00e9poca para visitar Gujarat<\/strong> se sit\u00faa entre los meses de septiembre y marzo. Su oferta tur\u00edstica es m\u00faltiple: atracciones culturales, artesan\u00edas tradicionales, paisajes magn\u00edficos, cocina deliciosa y playas encantadoras.<\/p>\n<div id=\"attachment_15549\" class=\"wp-caption alignnone\" style=\"width: 728px\"><a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15549 size-large\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg\" alt=\"Ahmedabad\" width=\"728\" height=\"410\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-300x169.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-728x410.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-363x204.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-462x260.jpg 462w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3.jpg 1200w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Wikipedia Commons<\/p><\/div>\n<p><strong>La ciudad principal de Gujarat es Ahmedabad<\/strong>, centro de negocios del estado. Se halla <strong>comunicada con <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/visitar-delhi-descubre-la-puerta-de-india-y-su-historia\/\" target=\"_blank\" rel=\"noopener\">Delhi<\/a> y <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/24-horas-en-mumbai\/\" target=\"_blank\" rel=\"noopener\">Mumbai<\/a> por avi\u00f3n y ferrocarril<\/strong>. Es una ciudad que combina un pasado hist\u00f3rico y un presente sumamente din\u00e1mico. Los principales lugares a visitar son la Mezquita Ahmed Shah, Balvatika, el Fuerte Bhadra, el Stepwell Dada Hari, el Ghummat de Daria Khan o el lago Kankaria.<\/p>\n<p>En 2017, <strong><a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/ahmedabad-ciudad-india-patrimonio-unesco\/\" target=\"_blank\" rel=\"noopener\">Ahmedabad<\/a> fue la primera ciudad de India en ser nombrada patrimonio de la Unesco<\/strong>.<\/p>\n<div id=\"attachment_16375\" class=\"wp-caption alignnone\" style=\"width: 800px\"><a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/bernard.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16375 size-full\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/bernard.jpg\" alt=\"gujarat-lothal\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/bernard.jpg 800w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/bernard-300x200.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/bernard-728x485.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/bernard-363x242.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/bernard-462x308.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Bernard Magnon<\/p><\/div>\n<p>Otro de los lugares cercanos que se puede visitar es la ciudad de <strong>Lothal, a 80 kil\u00f3metros de Ahmedabad<\/strong>. Conocido como \u00abel lugar de los muertos\u00bb, fue un puerto c\u00e9lebre durante la \u00e9poca de la civilizaci\u00f3n Harappan.<\/p>\n<div id=\"attachment_16376\" class=\"wp-caption alignnone\" style=\"width: 800px\"><a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/vikram-ural.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16376 size-full\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/vikram-ural.jpg\" alt=\"gujarat-modhera\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/vikram-ural.jpg 800w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/vikram-ural-300x225.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/vikram-ural-728x546.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/vikram-ural-363x272.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/vikram-ural-462x347.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Vikram Ural<\/p><\/div>\n<p><strong>Modhera<\/strong>, a 106 kil\u00f3metros, es el lugar donde se encuentra <strong>el templo del Sol<\/strong>, un\u00a0 magn\u00edfico ejemplo de arquitectura religiosa. Fue construido en 1026 y est\u00e1 dedicado al Dios Sol. Uno de los mejores\u00a0<a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/cultura\/templos-de-la-india\/\" target=\"_blank\" rel=\"noopener\">templos de India<\/a>.<\/p>\n<div id=\"attachment_16377\" class=\"wp-caption alignnone\" style=\"width: 800px\"><a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/manisitlani.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16377 size-full\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/manisitlani.jpg\" alt=\"gujarat-champaner-pavagadh\" width=\"800\" height=\"600\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/manisitlani.jpg 800w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/manisitlani-300x225.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/manisitlani-728x546.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/manisitlani-363x272.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/10\/manisitlani-462x347.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><p class=\"wp-caption-text\">\u00a9 Manisitlani<\/p><\/div>\n<p><strong>Vadodara<\/strong>, a 118 kil\u00f3metros de Ahmedabad, es una ciudad con bellos jardines y palacios. Es tambi\u00e9n la capital del estado en lo que se refiere a comercio e industria. En esta ciudad se pueden visitar lugares como el Palacio de Lakshmi Vilas, el Planetario Sardar Patel o <strong>Champaner Pavagadh, <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/india-patrimonio-de-la-humanidad\/\" target=\"_blank\" rel=\"noopener\">patrimonio mundial de la Unesco<\/a><\/strong> situado a 47 kil\u00f3metros de Vadodara.<\/p>\n<p>Gujarat, uno de los mejores estados para apreciar la historia durante un <a href=\"https:\/\/www.lasociedadgeografica.com\/nuestros-viajes\/india\/\" target=\"_blank\" rel=\"noopener\">viaje a India<\/a>.<\/p>\n<p><span class=\"s1\"><div class=\"SGIcontact\"><form id=\"sf_shortcode_SGIcontact_0F\" action=\"\/contacto\/\" method=\"post\" class=\"SGIcontactwidget_form\"><p style=\"text-align:center;font-style:italic;font-size:14px;padding-bottom:10px\" id=\"sf_shortcode_SGIcontact_0FP\">\u00bfQuieres que te dise\u00f1emos un viaje exclusivo al Subcontinente Indio?<\/p>\n<div style=\"text-align:center\" id=\"sf_shortcode_SGIcontact_0FD\"><input type=\"submit\" value=\"Cont\u00e1ctanos Aqu\u00ed\" \/>\n<\/div><\/form>\n<\/div><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gujarat es un estado din\u00e1mico situado en el oeste de India, famoso a su vez por su vibrante colorido y su religiosidad, al que se puede acceder f\u00e1cilmente por los aeropuertos internacionales de Delhi, Mumbai &hellip;<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,2881],"tags":[],"class_list":["post-16372","post","type-post","status-publish","format-standard","hentry","category-sgi","category-viajes-india"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gujarat: magia y monumentos Unesco en India<\/title>\n<meta name=\"description\" content=\"Gujarat, al noroeste de la India, es un estado que destaca por sus colores, religiosidad y ciudades dignas de ser nombradas patrimonio de la Unesco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gujarat: magia y monumentos Unesco en India\" \/>\n<meta property=\"og:description\" content=\"Gujarat, al noroeste de la India, es un estado que destaca por sus colores, religiosidad y ciudades dignas de ser nombradas patrimonio de la Unesco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de viajes a India\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-08T08:05:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg\" \/>\n<meta name=\"author\" content=\"Sociedad Geogr\u00e1fica de las Indias\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sociedad Geogr\u00e1fica de las Indias\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/\"},\"author\":{\"name\":\"Sociedad Geogr\u00e1fica de las Indias\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/5dedf86cdf71a82e0de5334ad35aacc6\"},\"headline\":\"Gujarat: magia y monumentos Unesco en India\",\"datePublished\":\"2018-02-08T08:05:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/\"},\"wordCount\":384,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/2017\\\/07\\\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg\",\"articleSection\":[\"SGI\",\"Viajes India\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/\",\"name\":\"Gujarat: magia y monumentos Unesco en India\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/2017\\\/07\\\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg\",\"datePublished\":\"2018-02-08T08:05:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/5dedf86cdf71a82e0de5334ad35aacc6\"},\"description\":\"Gujarat, al noroeste de la India, es un estado que destaca por sus colores, religiosidad y ciudades dignas de ser nombradas patrimonio de la Unesco.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/2017\\\/07\\\/baps_swaminarayan_temple_ahmedabad_3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/2017\\\/07\\\/baps_swaminarayan_temple_ahmedabad_3.jpg\",\"width\":1200,\"height\":675,\"caption\":\"\u00a9 Wikipedia Commons\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/gujarat-estado-de-unesco-india\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gujarat: magia y monumentos Unesco en India\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\",\"name\":\"Blog de viajes a India\",\"description\":\"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/5dedf86cdf71a82e0de5334ad35aacc6\",\"name\":\"Sociedad Geogr\u00e1fica de las Indias\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f36f96632929c6885a4d063ade7ca77074dbad67ddec0c0b842134e274de87e5?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f36f96632929c6885a4d063ade7ca77074dbad67ddec0c0b842134e274de87e5?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f36f96632929c6885a4d063ade7ca77074dbad67ddec0c0b842134e274de87e5?s=96&r=g\",\"caption\":\"Sociedad Geogr\u00e1fica de las Indias\"},\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gujarat: magia y monumentos Unesco en India","description":"Gujarat, al noroeste de la India, es un estado que destaca por sus colores, religiosidad y ciudades dignas de ser nombradas patrimonio de la Unesco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/","og_locale":"es_ES","og_type":"article","og_title":"Gujarat: magia y monumentos Unesco en India","og_description":"Gujarat, al noroeste de la India, es un estado que destaca por sus colores, religiosidad y ciudades dignas de ser nombradas patrimonio de la Unesco.","og_url":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/","og_site_name":"Blog de viajes a India","article_published_time":"2018-02-08T08:05:48+00:00","og_image":[{"url":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg","type":"","width":"","height":""}],"author":"Sociedad Geogr\u00e1fica de las Indias","twitter_misc":{"Escrito por":"Sociedad Geogr\u00e1fica de las Indias","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#article","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/"},"author":{"name":"Sociedad Geogr\u00e1fica de las Indias","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/5dedf86cdf71a82e0de5334ad35aacc6"},"headline":"Gujarat: magia y monumentos Unesco en India","datePublished":"2018-02-08T08:05:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/"},"wordCount":384,"commentCount":1,"image":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg","articleSection":["SGI","Viajes India"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/","url":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/","name":"Gujarat: magia y monumentos Unesco en India","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#primaryimage"},"image":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3-1024x576.jpg","datePublished":"2018-02-08T08:05:48+00:00","author":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/5dedf86cdf71a82e0de5334ad35aacc6"},"description":"Gujarat, al noroeste de la India, es un estado que destaca por sus colores, religiosidad y ciudades dignas de ser nombradas patrimonio de la Unesco.","breadcrumb":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#primaryimage","url":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3.jpg","contentUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/2017\/07\/baps_swaminarayan_temple_ahmedabad_3.jpg","width":1200,"height":675,"caption":"\u00a9 Wikipedia Commons"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/gujarat-estado-de-unesco-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lasociedadgeografica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gujarat: magia y monumentos Unesco en India"}]},{"@type":"WebSite","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website","url":"https:\/\/www.lasociedadgeografica.com\/blog\/","name":"Blog de viajes a India","description":"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasociedadgeografica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/5dedf86cdf71a82e0de5334ad35aacc6","name":"Sociedad Geogr\u00e1fica de las Indias","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f36f96632929c6885a4d063ade7ca77074dbad67ddec0c0b842134e274de87e5?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f36f96632929c6885a4d063ade7ca77074dbad67ddec0c0b842134e274de87e5?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f36f96632929c6885a4d063ade7ca77074dbad67ddec0c0b842134e274de87e5?s=96&r=g","caption":"Sociedad Geogr\u00e1fica de las Indias"},"url":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/16372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/comments?post=16372"}],"version-history":[{"count":5,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/16372\/revisions"}],"predecessor-version":[{"id":16539,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/16372\/revisions\/16539"}],"wp:attachment":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/media?parent=16372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/categories?post=16372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/tags?post=16372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}