{"id":26002,"date":"2024-07-02T10:13:16","date_gmt":"2024-07-02T08:13:16","guid":{"rendered":"https:\/\/www.lasociedadgeografica.com\/blog\/?p=26002"},"modified":"2024-07-02T10:13:16","modified_gmt":"2024-07-02T08:13:16","slug":"madhu-seafood-kerala","status":"publish","type":"post","link":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/","title":{"rendered":"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;26002&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;2&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;6&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;5\\\/5 - (2 votos)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala&quot;,&quot;width&quot;:&quot;137&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 137px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            5\/5 - (2 votos)    <\/div>\n    <\/div>\n<p><div id=\"attachment_26007\" class=\"wp-caption aligncenter\" style=\"width: 928px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26007 size-full\" title=\"madhu seafood restaurant\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg\" alt=\"madhu seafood restaurant \" width=\"928\" height=\"696\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg 928w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor-300x225.jpeg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor-728x546.jpeg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor-363x272.jpeg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor-462x347.jpeg 462w\" sizes=\"auto, (max-width: 928px) 100vw, 928px\" \/><p class=\"wp-caption-text\">\u00bfBuscando un buen restaurante en Kerala? @cheftzac<\/p><\/div><br \/>\n<a name=\"smore-\"><\/a><br \/>\n<i><span class=\"entradilla\">En un lugar perdido de la selva de Kerala, Madhu recibe a todos sus visitantes bajo la promesa cumplida de hacerles vivir una experiencia tan c\u00e1lida como deliciosa. \u00a1Bienvenidos Madhu Seafood Restaurant!<\/span><\/i><\/p>\n<p>Escrito por: Alberto Piernas<\/p>\n<p><!--more--><\/p>\n<h2>Madhu Seafood Restaurant: una comida (o una vida) en uno de los mejores restaurantes de Kerala<\/h2>\n<div id=\"attachment_26003\" class=\"wp-caption aligncenter\" style=\"width: 1080px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26003 size-full\" title=\"madhu cocinando en su restaurante \" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/cheftzac-madhus-restaurant.jpeg\" alt=\"madhu seafood restaurant \" width=\"1080\" height=\"1350\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/cheftzac-madhus-restaurant.jpeg 1080w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/cheftzac-madhus-restaurant-240x300.jpeg 240w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/cheftzac-madhus-restaurant-819x1024.jpeg 819w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/cheftzac-madhus-restaurant-728x910.jpeg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/cheftzac-madhus-restaurant-363x454.jpeg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/cheftzac-madhus-restaurant-462x578.jpeg 462w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><p class=\"wp-caption-text\">Madhu, toda una leyenda en el estado de Kerala, en India del Sur. @cheftzac<\/p><\/div>\n<p>En alg\u00fan momento de regreso a <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/viajar-a-kochi-en-2020-a-lonely-planet-le-gustan-las-especias\/\" target=\"_blank\" rel=\"noopener\">Kochi<\/a> desde <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/un-dia-en-los-backwaters-de-kerala\/\" target=\"_blank\" rel=\"noopener\">Alleppey<\/a> y sus <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/kottayam-backwaters-kerala\/\" target=\"_blank\" rel=\"noopener\">backwaters<\/a>, la selva evoca un verde m\u00e1s intenso, la moto no resistir\u00e1 las carreteras mojadas a causa de los \u00faltimos coletazos del monz\u00f3n y la traves\u00eda invita a una parada. Nos han hablado de <strong>Madhu Seafood Restaurant<\/strong>, toda una instituci\u00f3n en la <strong>zona de Cherthala<\/strong>, justo al lado de la autopista a Marari, pero no nos lo creemos hasta que entramos.<\/p>\n<p><strong>Madhu<\/strong>, que est\u00e1 en todo, nos localiza desde el otro lado del patio y viene hacia nosotros para darnos un abrazo. Tiene un bigote tupido\u00a0 y una sonrisa capaz de traer luz a una casa entera. Madhu es una persona agradecida, se percibe desde lejos, a juzgar por las veces que inclina la cabeza, intercala abrazos y vigila que cada uno de sus invitados, que no clientes, <strong>disfruten de su comida<\/strong>.<\/p>\n<div id=\"attachment_26005\" class=\"wp-caption aligncenter\" style=\"width: 1080px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26005 size-full\" title=\"madhu seafood restaurant\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-2.jpg\" alt=\"pescado en madhu seafood restaurant\" width=\"1080\" height=\"1350\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-2.jpg 1080w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-2-240x300.jpg 240w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-2-819x1024.jpg 819w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-2-728x910.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-2-363x454.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-2-462x578.jpg 462w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><p class=\"wp-caption-text\">El pescado fresco se cocina con diferentes salsas y especias. @cheftzac<\/p><\/div>\n<p>Este restaurante es famoso en toda la zona gracias al buenhacer de Madhu pero, tambi\u00e9n, la materia prima con la que trabaja. Sus delicias se nutren de <strong>marisco fresco y delicioso<\/strong> que se preparan a vista del cliente, en un patio destartalado que inspira una certera confianza. La disposici\u00f3n de los asientos es informal y se despliega a trav\u00e9s del jard\u00edn. Las horas punta se sienten, pero merece la pena aguardar al fest\u00edn. Tanto, que incluso se rumorea que <span class=\"Y2IQFc\" lang=\"es\">Mohan Lal, la superestrella de Mollywood, pide comida para llevar en este restuarante de vez en cuando.<\/span><\/p>\n<p>Aqu\u00ed los mariscos se cocinan en su total diversidad, <strong>acompa\u00f1ados de arroz<\/strong>\u00a0y guarniciones de verduras a nuestra elecci\u00f3n. Las gambas fritas y el curry de pescado de agua dulce son algunas de sus recomendaciones, si bien el pur\u00e9 de mandioca, adem\u00e1s de sus langostinos fritos en <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/gastronomia\/gastronomia-india-vista-por-world-gourmet-society\/\" target=\"_blank\" rel=\"noopener\">ghee y masala rojo intenso<\/a>, arroz y sambar, son deliciosos. Todo tipo de guarniciones que ensalzan la experiencia y te hacen repetir hasta que ya no puedes m\u00e1s.<\/p>\n<div id=\"attachment_26006\" class=\"wp-caption aligncenter\" style=\"width: 1080px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26006 size-full\" title=\"comida en madhu seafood restaurant \" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-3.jpg\" alt=\"plato t\u00edpico en madhu seafood restaurant\" width=\"1080\" height=\"1350\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-3.jpg 1080w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-3-240x300.jpg 240w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-3-819x1024.jpg 819w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-3-728x910.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-3-363x454.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/madhu-3-462x578.jpg 462w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><p class=\"wp-caption-text\">Los men\u00fas de Madhu se basan en diferentes platillos irresistibles. @cheftzac<\/p><\/div>\n<p>Madhu se pasa a ver qu\u00e9 tal todo, se sienta a la mesa, te incita a comer con la mano y te ense\u00f1a incluso c\u00f3mo se ajusta el dothi &#8211; t\u00edpica pieza de tela que los hombres de India del Sur lucen a modo de pantal\u00f3n -. Alguien limpia la plancha, otra persona vuelve para reponer el men\u00fa, un enorme caracol deambula entre los muros del restaurante y te inunda <strong>la certeza de estar en el lugar correcto, en el momento adecuado<\/strong>.<\/p>\n<p>Sin duda, Madhu Seafood Restaurant es una de esas serendipias gastron\u00f3micas que <strong>no pueden faltar en tu ruta por el estado de Kerala<\/strong>, especialmente si te dispones a visitar los <em>backwaters<\/em> de Alleppey.<\/p>\n<p>Descubre el restaurante de Madhu durante tu pr\u00f3ximo <a href=\"https:\/\/www.lasociedadgeografica.com\/nuestros-viajes\/india\/\" target=\"_blank\" rel=\"noopener\">viaje a India<\/a>.<\/p>\n<div class=\"SGIcontact\"><form id=\"sf_shortcode_SGIcontact_0F\" action=\"\/contacto\/\" method=\"post\" class=\"SGIcontactwidget_form\"><p style=\"text-align:center;font-style:italic;font-size:14px;padding-bottom:10px\" id=\"sf_shortcode_SGIcontact_0FP\">\u00bfQuieres que te dise\u00f1emos un viaje exclusivo al Subcontinente Indio?<\/p>\n<div style=\"text-align:center\" id=\"sf_shortcode_SGIcontact_0FD\"><input type=\"submit\" value=\"Cont\u00e1ctanos Aqu\u00ed\" \/>\n<\/div><\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En un lugar perdido de la selva de Kerala, Madhu recibe a todos sus visitantes bajo la promesa cumplida de hacerles vivir una experiencia tan c\u00e1lida como deliciosa. \u00a1Bienvenidos Madhu Seafood Restaurant! Escrito por: Alberto &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2881],"tags":[],"class_list":["post-26002","post","type-post","status-publish","format-standard","hentry","category-viajes-india"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala<\/title>\n<meta name=\"description\" content=\"Madhu Seafood Restaurant es mucho m\u00e1s que un restaurante: una instituci\u00f3n en el coraz\u00f3n de la selva de Kerala.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala\" \/>\n<meta property=\"og:description\" content=\"Madhu Seafood Restaurant es mucho m\u00e1s que un restaurante: una instituci\u00f3n en el coraz\u00f3n de la selva de Kerala.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de viajes a India\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-02T08:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg\" \/>\n<meta name=\"author\" content=\"SGI\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SGI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/\"},\"author\":{\"name\":\"SGI\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"headline\":\"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala\",\"datePublished\":\"2024-07-02T08:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/\"},\"wordCount\":595,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/tripadvisor.jpeg\",\"articleSection\":[\"Viajes India\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/\",\"name\":\"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/tripadvisor.jpeg\",\"datePublished\":\"2024-07-02T08:13:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"description\":\"Madhu Seafood Restaurant es mucho m\u00e1s que un restaurante: una instituci\u00f3n en el coraz\u00f3n de la selva de Kerala.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/tripadvisor.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/tripadvisor.jpeg\",\"width\":928,\"height\":696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-india\\\/madhu-seafood-kerala\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\",\"name\":\"Blog de viajes a India\",\"description\":\"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\",\"name\":\"SGI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"caption\":\"SGI\"},\"description\":\"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\\\/\\\/www.lasociedadgeografica.com\",\"sameAs\":[\"https:\\\/\\\/www.lasociedadgeografica.com\"],\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala","description":"Madhu Seafood Restaurant es mucho m\u00e1s que un restaurante: una instituci\u00f3n en el coraz\u00f3n de la selva de Kerala.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/","og_locale":"es_ES","og_type":"article","og_title":"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala","og_description":"Madhu Seafood Restaurant es mucho m\u00e1s que un restaurante: una instituci\u00f3n en el coraz\u00f3n de la selva de Kerala.","og_url":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/","og_site_name":"Blog de viajes a India","article_published_time":"2024-07-02T08:13:16+00:00","og_image":[{"url":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg","type":"","width":"","height":""}],"author":"SGI","twitter_misc":{"Escrito por":"SGI","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#article","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/"},"author":{"name":"SGI","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"headline":"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala","datePublished":"2024-07-02T08:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/"},"wordCount":595,"commentCount":0,"image":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg","articleSection":["Viajes India"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/","url":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/","name":"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#primaryimage"},"image":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg","datePublished":"2024-07-02T08:13:16+00:00","author":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"description":"Madhu Seafood Restaurant es mucho m\u00e1s que un restaurante: una instituci\u00f3n en el coraz\u00f3n de la selva de Kerala.","breadcrumb":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#primaryimage","url":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg","contentUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/tripadvisor.jpeg","width":928,"height":696},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/madhu-seafood-kerala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lasociedadgeografica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Madhu Seafood Restaurant: m\u00e1s que mariscos en Kerala"}]},{"@type":"WebSite","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website","url":"https:\/\/www.lasociedadgeografica.com\/blog\/","name":"Blog de viajes a India","description":"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasociedadgeografica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2","name":"SGI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","caption":"SGI"},"description":"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\/\/www.lasociedadgeografica.com","sameAs":["https:\/\/www.lasociedadgeografica.com"],"url":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/26002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/comments?post=26002"}],"version-history":[{"count":2,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/26002\/revisions"}],"predecessor-version":[{"id":26009,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/26002\/revisions\/26009"}],"wp:attachment":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/media?parent=26002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/categories?post=26002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/tags?post=26002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}