{"id":27466,"date":"2025-11-19T07:15:44","date_gmt":"2025-11-19T06:15:44","guid":{"rendered":"https:\/\/www.lasociedadgeografica.com\/blog\/?p=27466"},"modified":"2025-11-27T11:38:23","modified_gmt":"2025-11-27T10:38:23","slug":"gathering-sri-lanka","status":"publish","type":"post","link":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/","title":{"rendered":"\u00bfQu\u00e9 es el famoso \u00abThe Gathering\u00bb de Sri Lanka?"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;27466&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;2&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;6&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;5\\\/5 - (2 votos)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;\u00bfQu\u00e9 es el famoso \\u0026quot;The Gathering\\u0026quot; de Sri Lanka?&quot;,&quot;width&quot;:&quot;137&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 137px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 6px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            5\/5 - (2 votos)    <\/div>\n    <\/div>\n<p><div id=\"attachment_27468\" class=\"wp-caption aligncenter\" style=\"width: 750px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27468 size-full\" title=\"elefantes en el lago minneriya\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg\" alt=\"the gathering sri lanka\" width=\"750\" height=\"533\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg 750w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants-300x213.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants-728x517.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants-363x258.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants-462x328.jpg 462w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><p class=\"wp-caption-text\">The Gathering, el gran milagro de la naturaleza en Sri Lanka. \u00a9 CBS<\/p><\/div><br \/>\n<a name=\"smore-\"><\/a><br \/>\n<i><span class=\"entradilla\">La \u00abGran Reuni\u00f3n\u00bb de Sri Lanka supone uno de los espect\u00e1culos naturales m\u00e1s fascinantes del mundo. Especialmente, si sabes en qu\u00e9 momento acudir a la llamada de la isla de las serendipias (y los elefantes).\u00a0<\/span><\/i><\/p>\n<p>Por Alberto Piernas<\/p>\n<p><!--more--><\/p>\n<div id=\"attachment_27469\" class=\"wp-caption aligncenter\" style=\"width: 1080px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27469 size-full\" title=\"elefante en minneriya sri lanka \" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/wherethesoulwander.jpg\" alt=\"elefante en minneriya the gathering\" width=\"1080\" height=\"1350\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/wherethesoulwander.jpg 1080w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/wherethesoulwander-240x300.jpg 240w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/wherethesoulwander-819x1024.jpg 819w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/wherethesoulwander-728x910.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/wherethesoulwander-363x454.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/wherethesoulwander-462x578.jpg 462w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><p class=\"wp-caption-text\">Entre julio y agosto, algo pasa en Sri Lanka. @wherethesoulwander<\/p><\/div>\n<p>No es ning\u00fan secreto que<strong> <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/puede-un-hotel-salvar-la-naturaleza-si-y-se-llama-jetwing-vil-uyana-en-sri-lanka\/\" target=\"_blank\" rel=\"noopener\">Sri Lanka<\/a> es uno de los pa\u00edses con mayor biodiversidad del mundo<\/strong>. Lo confirman cinco de las siete especies de tortugas marinas que alcanzan sus costas, sus <strong>casi 500 especies de aves<\/strong> y, claro, <strong>m\u00e1s de <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/spa-elefantes-india\/\" target=\"_blank\" rel=\"noopener\">6000 elefantes<\/a> convertidos en iconos de la isla<\/strong>.<\/p>\n<p>Un tapiz natural que nos sumerge en experiencias alucinantes que van desde los<a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/naturaleza\/que-ver-en-sri-lanka-ballenas\/\" target=\"_blank\" rel=\"noopener\"><strong> avistamientos de ballenas<\/strong><\/a> hasta <em>ecolodges<\/em> ba\u00f1ados por safaris casi infinitos, pero tambi\u00e9n \u00abeventos\u00bb que se dan de forma exclusiva en ciertas \u00e9pocas del a\u00f1o. Uno de los m\u00e1s importantes es el conocido como <strong>\u00abThe Gathering\u00bb o \u00abGran Reuni\u00f3n de Elefantes\u00bb<\/strong>.<\/p>\n<p>Te contamos en qu\u00e9 consiste este espect\u00e1culo de la naturaleza que no te puedes perder.<\/p>\n<h2>The Gathering: el gran peregrinaje de la naturaleza<\/h2>\n<div id=\"attachment_27467\" class=\"wp-caption aligncenter\" style=\"width: 1920px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27467 size-full\" title=\"elefantes sri lanka\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance.jpg\" alt=\"the gatheringg sri lanka \" width=\"1920\" height=\"500\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance.jpg 1920w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance-300x78.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance-1024x267.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance-1536x400.jpg 1536w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance-728x190.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance-363x95.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/sri-lanka-tour-alliance-462x120.jpg 462w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><p class=\"wp-caption-text\">M\u00e1s de 300 elefantes migran al sur de Sri Lanka. \u00a9 Love SL<\/p><\/div>\n<p><strong>El elefante es uno de los mayores s\u00edmbolos de Sri Lanka<\/strong>. Sin embargo, <strong>su h\u00e1bitat natural se ha visto en peligro<\/strong> durante los \u00faltimos a\u00f1os debido a conflictos con los agricultores, nuevos asentamientos o problemas de urbanismo que friccionan con sus espacios vitales.<\/p>\n<p>De ah\u00ed que las alternativas para ver elefantes requieran de la necesaria investigaci\u00f3n a fin de interactuar con ellos de una forma consciente: hay quienes prefieren optar por<strong> los orfanatos de elefantes<\/strong> (atentos siempre a la letra peque\u00f1a), las inmersiones en <strong>parques naturales como <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/curiosidades\/udawalawe-national-park\/\" target=\"_blank\" rel=\"noopener\">Udawalawe<\/a> o <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/consejos-para-hacer-un-safari-en-sri-lanka\/\" target=\"_blank\" rel=\"noopener\">Wilpattu<\/a><\/strong> o, en este caso, una experiencia tan recomendable como <strong>The Gathering<\/strong>.<\/p>\n<p>Esta \u00abGran Reuni\u00f3n\u00bb consiste en<strong> la migraci\u00f3n de m\u00e1s de 300 elefantes<\/strong> &#8211; aunque se ha llegado a alcanzar la marca de 700 elefantes &#8211; desde las provincias del norte de Sri Lanka huyendo de la \u00e9poca de sequ\u00eda para<strong> buscar pasto y alimentos en el sur.<\/strong> Esta concentraci\u00f3n que <strong>tiene lugar <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/festividades\/fiestas-en-sri-lanka\/\" target=\"_blank\" rel=\"noopener\">entre julio y octubre<\/a> <\/strong>recorre la mitad norte del pa\u00eds hasta alcanzar el lecho del<strong> lago de <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/elefantes-en-sri-lanka-minneriya\/\" target=\"_blank\" rel=\"noopener\">Minneriya<\/a><\/strong>, considerada como una de las mejores reservas para avistar elefantes.<\/p>\n<div id=\"attachment_27470\" class=\"wp-caption aligncenter\" style=\"width: 1200px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27470 size-full\" title=\"elefantes minneriya sri lanka\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/migracion-elefantes-sri-lanka-cbs.jpg\" alt=\"the gathering sri lanka\" width=\"1200\" height=\"630\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/migracion-elefantes-sri-lanka-cbs.jpg 1200w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/migracion-elefantes-sri-lanka-cbs-300x158.jpg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/migracion-elefantes-sri-lanka-cbs-1024x538.jpg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/migracion-elefantes-sri-lanka-cbs-728x382.jpg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/migracion-elefantes-sri-lanka-cbs-363x191.jpg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/migracion-elefantes-sri-lanka-cbs-462x243.jpg 462w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p class=\"wp-caption-text\">El avistamiento de elefantes en Sri Lanka durante The Gathering es toda una serendipia. \u00a9 Love SL<\/p><\/div>\n<p>Durante la estaci\u00f3n seca, las aguas del lago se evaporan parcialmente, por lo que dejan al descubierto<strong> tapices de praderas verdes y f\u00e9rtiles<\/strong> que suponen el para\u00edso para estos queridos animales. De esta forma, los elefante sacian su sed, se refrescan en el agua y se prestan a <strong>ser observados sin irrumpir en su h\u00e1bitat de forma invasiva<\/strong>. Adem\u00e1s, los amplios bosques que rodean el lago les sirve de cobijo para protegerse del calor.<\/p>\n<p>Este fen\u00f3meno provoca que los elefantes formen <strong>grandes manadas<\/strong> y, por ende, nos regalen estampas inolvidables en una \u00e9poca muy concreta del a\u00f1o. Aunque las fechas pueden variar seg\u00fan el a\u00f1o, <strong>agosto y septiembre suelen ser los dos mejores meses<\/strong> para acudir a la llamada de la reuni\u00f3n. Adem\u00e1s, los elefantes tienden a evitar el sol durante el d\u00eda, por lo que los mejores momentos para realizar <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-india\/avistar-leopardos-subcontinente-indio-mejores-lugares\/\" target=\"_blank\" rel=\"noopener\">un avistamiento<\/a> suele ser <strong>entre las 3 y las 6 de la tarde, coincidiendo con el atardecer<\/strong>. Un momento m\u00e1gico para sucumbir a los caprichos de la naturaleza.<\/p>\n<div id=\"attachment_24798\" class=\"wp-caption aligncenter\" style=\"width: 1600px\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24798 size-full\" title=\"elefantes en lago minneriya\" src=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance.jpeg\" alt=\"la reunion sri lanka\" width=\"1600\" height=\"1067\" srcset=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance.jpeg 1600w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance-300x200.jpeg 300w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance-1024x683.jpeg 1024w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance-1536x1024.jpeg 1536w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance-728x485.jpeg 728w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance-363x242.jpeg 363w, https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/elephant-gathering-gallery-2-sri-lanka-tourism-alliance-462x308.jpeg 462w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><p class=\"wp-caption-text\">Agosto y septiembre son los mejores meses para avistar elefantes. \u00a9 Pixabay<\/p><\/div>\n<p>A su vez, Minneriya supone <strong>una perfecta extensi\u00f3n del <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/triangulo-cultural-sri-lanka-experiencias-diferentes\/\" target=\"_blank\" rel=\"noopener\">Tri\u00e1ngulo Cultural<\/a> de Sri Lanka<\/strong>, formado por iconos como<strong> <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/que-ver-en-sigiriya-la-roca-mas-bonita-del-mundo-esta-en-sri-lanka\/\" target=\"_blank\" rel=\"noopener\">Sigiriya<\/a>, las ciudades imperiales de <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/monumentos\/polonnaruwa-en-sri-lanka\/\" target=\"_blank\" rel=\"noopener\">Pollonnaruwa<\/a> y <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/cultura\/anuradhapura\/\" target=\"_blank\" rel=\"noopener\">Anuradhapura<\/a> o las <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/mitologia-y-religion\/las-cuevas-de-dambulla-sri-lanka\/\" target=\"_blank\" rel=\"noopener\">Cuevas de Dambulla<\/a><\/strong>, por lo que si te encuentras de visita en esta zona siempre puedes reservar un d\u00eda m\u00e1s para disfrutar de esta experiencia.<\/p>\n<p>Ante todo, recomendamos seguir las normas y reglamentos del parque y, a ser posible, contar con soporte local en forma de <a href=\"https:\/\/www.lasociedadgeografica.com\/blog\/sgi\/que-deberia-saber-tu-guia-acompanante-en-india-de-ti\/\" target=\"_blank\" rel=\"noopener\">gu\u00eda<\/a> para descubrir todos los secretos de The Gathering.<\/p>\n<p>\u00bfTe gustar\u00eda disfrutar de este espect\u00e1culo de la naturaleza durante <strong>tu pr\u00f3ximo <a href=\"https:\/\/www.lasociedadgeografica.com\/info\/viaje-a-sri-lanka\/\" target=\"_blank\" rel=\"noopener\">viaje a Sri Lanka<\/a><\/strong>?<\/p>\n<div class=\"SGIcontact\"><form id=\"sf_shortcode_SGIcontact_0F\" action=\"\/contacto\/\" method=\"post\" class=\"SGIcontactwidget_form\"><p style=\"text-align:center;font-style:italic;font-size:14px;padding-bottom:10px\" id=\"sf_shortcode_SGIcontact_0FP\">\u00bfQuieres que te dise\u00f1emos un viaje exclusivo al Subcontinente Indio?<\/p>\n<div style=\"text-align:center\" id=\"sf_shortcode_SGIcontact_0FD\"><input type=\"submit\" value=\"Cont\u00e1ctanos Aqu\u00ed\" \/>\n<\/div><\/form>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La \u00abGran Reuni\u00f3n\u00bb de Sri Lanka supone uno de los espect\u00e1culos naturales m\u00e1s fascinantes del mundo. Especialmente, si sabes en qu\u00e9 momento acudir a la llamada de la isla de las serendipias (y los elefantes).\u00a0 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,2885],"tags":[],"class_list":["post-27466","post","type-post","status-publish","format-standard","hentry","category-sgi","category-viajes-sri-lanka"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es el famoso &quot;The Gathering&quot; de Sri Lanka?<\/title>\n<meta name=\"description\" content=\"The Gathering o &quot;Gran Reuni\u00f3n&quot; de Sri Lanka supone el mayor espect\u00e1culo natural de la isla de las serendipias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es el famoso &quot;The Gathering&quot; de Sri Lanka?\" \/>\n<meta property=\"og:description\" content=\"The Gathering o &quot;Gran Reuni\u00f3n&quot; de Sri Lanka supone el mayor espect\u00e1culo natural de la isla de las serendipias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de viajes a India\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T06:15:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-27T10:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SGI\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SGI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/\"},\"author\":{\"name\":\"SGI\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"headline\":\"\u00bfQu\u00e9 es el famoso \u00abThe Gathering\u00bb de Sri Lanka?\",\"datePublished\":\"2025-11-19T06:15:44+00:00\",\"dateModified\":\"2025-11-27T10:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/\"},\"wordCount\":756,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/the-gathering-elephants.jpg\",\"articleSection\":[\"SGI\",\"Viajes Sri Lanka\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/\",\"name\":\"\u00bfQu\u00e9 es el famoso \\\"The Gathering\\\" de Sri Lanka?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/the-gathering-elephants.jpg\",\"datePublished\":\"2025-11-19T06:15:44+00:00\",\"dateModified\":\"2025-11-27T10:38:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\"},\"description\":\"The Gathering o \\\"Gran Reuni\u00f3n\\\" de Sri Lanka supone el mayor espect\u00e1culo natural de la isla de las serendipias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/the-gathering-elephants.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/uploads\\\/the-gathering-elephants.jpg\",\"width\":750,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/viajes-sri-lanka\\\/gathering-sri-lanka\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es el famoso \u00abThe Gathering\u00bb de Sri Lanka?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\",\"name\":\"Blog de viajes a India\",\"description\":\"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/4eb706084ebada5acb6f674d895232d2\",\"name\":\"SGI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g\",\"caption\":\"SGI\"},\"description\":\"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\\\/\\\/www.lasociedadgeografica.com\",\"sameAs\":[\"https:\\\/\\\/www.lasociedadgeografica.com\"],\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es el famoso \"The Gathering\" de Sri Lanka?","description":"The Gathering o \"Gran Reuni\u00f3n\" de Sri Lanka supone el mayor espect\u00e1culo natural de la isla de las serendipias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es el famoso \"The Gathering\" de Sri Lanka?","og_description":"The Gathering o \"Gran Reuni\u00f3n\" de Sri Lanka supone el mayor espect\u00e1culo natural de la isla de las serendipias.","og_url":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/","og_site_name":"Blog de viajes a India","article_published_time":"2025-11-19T06:15:44+00:00","article_modified_time":"2025-11-27T10:38:23+00:00","og_image":[{"width":750,"height":533,"url":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg","type":"image\/jpeg"}],"author":"SGI","twitter_misc":{"Escrito por":"SGI","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#article","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/"},"author":{"name":"SGI","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"headline":"\u00bfQu\u00e9 es el famoso \u00abThe Gathering\u00bb de Sri Lanka?","datePublished":"2025-11-19T06:15:44+00:00","dateModified":"2025-11-27T10:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/"},"wordCount":756,"commentCount":0,"image":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg","articleSection":["SGI","Viajes Sri Lanka"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/","url":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/","name":"\u00bfQu\u00e9 es el famoso \"The Gathering\" de Sri Lanka?","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#primaryimage"},"image":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg","datePublished":"2025-11-19T06:15:44+00:00","dateModified":"2025-11-27T10:38:23+00:00","author":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2"},"description":"The Gathering o \"Gran Reuni\u00f3n\" de Sri Lanka supone el mayor espect\u00e1culo natural de la isla de las serendipias.","breadcrumb":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#primaryimage","url":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg","contentUrl":"https:\/\/www.lasociedadgeografica.com\/blog\/uploads\/the-gathering-elephants.jpg","width":750,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/viajes-sri-lanka\/gathering-sri-lanka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lasociedadgeografica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es el famoso \u00abThe Gathering\u00bb de Sri Lanka?"}]},{"@type":"WebSite","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website","url":"https:\/\/www.lasociedadgeografica.com\/blog\/","name":"Blog de viajes a India","description":"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasociedadgeografica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/4eb706084ebada5acb6f674d895232d2","name":"SGI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3b6518b4778a72cb0cada5ad3bf7536bf8fd05c7dc636ba9c80f95598fc13469?s=96&r=g","caption":"SGI"},"description":"Sociedad Geogr\u00e1fica de las Indias, agencia especializada en viajes exclusivos y a medida a India. https:\/\/www.lasociedadgeografica.com","sameAs":["https:\/\/www.lasociedadgeografica.com"],"url":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/27466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/comments?post=27466"}],"version-history":[{"count":4,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/27466\/revisions"}],"predecessor-version":[{"id":27527,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/posts\/27466\/revisions\/27527"}],"wp:attachment":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/media?parent=27466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/categories?post=27466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/tags?post=27466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}