{"id":8,"name":"Nona Rubio","url":"http:\/\/nonarubio.musacomunica.es\/","description":"A Nona no le gusta viajar. Le apasiona viajar. Y tambi\u00e9n contar sus viajes en diferentes formatos. Desde un cuaderno de bit\u00e1cora de una expedici\u00f3n al Himalaya acompa\u00f1ando al alpinista aragon\u00e9s Carlos Pauner hasta los 4.900 metros de altura; a los guiones de su propia serie de viajes \u201cEl Camino m\u00e1s Largo\u201d (GeoPlaneta TV).  \r\nLa primera vez que puso un pie en India supo que repetir\u00eda. Su flechazo con el segundo pa\u00eds m\u00e1s poblado del mundo fue inmediato. Y eso que Nona no es amiga de las multitudes. Pero lo de India es otra historia. Por eso ahora est\u00e1 aqu\u00ed. Para seguir contando historias que hablan de un pa\u00eds inabarcable con el que hay que ser paciente si lo que pretendemos es conocerlo por dentro.  + info: <a href=\"http:\/\/nonarubio.musacomunica.es\/\">nonarubio<\/a>","link":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/","slug":"nona_rubio","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=24&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=48&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=96&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nona Rubio, Autor en Blog de viajes a India<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Nona Rubio, Autor en Blog de viajes a India\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de viajes a India\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/9c6c575ad6da9798fdf2ec79a5234453?s=500&r=g\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/nona_rubio\\\/\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/nona_rubio\\\/\",\"name\":\"Nona Rubio, Autor en Blog de viajes a India\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/nona_rubio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/nona_rubio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/nona_rubio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivos por Nona Rubio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/\",\"name\":\"Blog de viajes a India\",\"description\":\"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/#\\\/schema\\\/person\\\/b3f7515b0befa8a16343ebf3bf602f0e\",\"name\":\"Nona Rubio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=96&r=g\",\"caption\":\"Nona Rubio\"},\"description\":\"A Nona no le gusta viajar. Le apasiona viajar. Y tambi\u00e9n contar sus viajes en diferentes formatos. Desde un cuaderno de bit\u00e1cora de una expedici\u00f3n al Himalaya acompa\u00f1ando al alpinista aragon\u00e9s Carlos Pauner hasta los 4.900 metros de altura; a los guiones de su propia serie de viajes \u201cEl Camino m\u00e1s Largo\u201d (GeoPlaneta TV). La primera vez que puso un pie en India supo que repetir\u00eda. Su flechazo con el segundo pa\u00eds m\u00e1s poblado del mundo fue inmediato. Y eso que Nona no es amiga de las multitudes. Pero lo de India es otra historia. Por eso ahora est\u00e1 aqu\u00ed. Para seguir contando historias que hablan de un pa\u00eds inabarcable con el que hay que ser paciente si lo que pretendemos es conocerlo por dentro. + info: nonarubio\",\"sameAs\":[\"http:\\\/\\\/nonarubio.musacomunica.es\\\/\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lasociedadgeografica.com\\\/blog\\\/author\\\/nona_rubio\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nona Rubio, Autor en Blog de viajes a India","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/","og_locale":"es_ES","og_type":"profile","og_title":"Nona Rubio, Autor en Blog de viajes a India","og_url":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/","og_site_name":"Blog de viajes a India","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/9c6c575ad6da9798fdf2ec79a5234453?s=500&r=g","type":"","width":"","height":""}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/","url":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/","name":"Nona Rubio, Autor en Blog de viajes a India","isPartOf":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.lasociedadgeografica.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Archivos por Nona Rubio"}]},{"@type":"WebSite","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#website","url":"https:\/\/www.lasociedadgeografica.com\/blog\/","name":"Blog de viajes a India","description":"Un lugar para Conocer India, con may\u00fasculas. El Blog de Sociedad Geogr\u00e1fica de las Indias.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lasociedadgeografica.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.lasociedadgeografica.com\/blog\/#\/schema\/person\/b3f7515b0befa8a16343ebf3bf602f0e","name":"Nona Rubio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bf18ee7fde0e9d49eab0aea4940b9c7efe777788dd6cddc8e6c52f980cdf262?s=96&r=g","caption":"Nona Rubio"},"description":"A Nona no le gusta viajar. Le apasiona viajar. Y tambi\u00e9n contar sus viajes en diferentes formatos. Desde un cuaderno de bit\u00e1cora de una expedici\u00f3n al Himalaya acompa\u00f1ando al alpinista aragon\u00e9s Carlos Pauner hasta los 4.900 metros de altura; a los guiones de su propia serie de viajes \u201cEl Camino m\u00e1s Largo\u201d (GeoPlaneta TV). La primera vez que puso un pie en India supo que repetir\u00eda. Su flechazo con el segundo pa\u00eds m\u00e1s poblado del mundo fue inmediato. Y eso que Nona no es amiga de las multitudes. Pero lo de India es otra historia. Por eso ahora est\u00e1 aqu\u00ed. Para seguir contando historias que hablan de un pa\u00eds inabarcable con el que hay que ser paciente si lo que pretendemos es conocerlo por dentro. + info: nonarubio","sameAs":["http:\/\/nonarubio.musacomunica.es\/"],"mainEntityOfPage":{"@id":"https:\/\/www.lasociedadgeografica.com\/blog\/author\/nona_rubio\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/users\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lasociedadgeografica.com\/blog\/wp-json\/wp\/v2\/users"}]}}